{"id":73,"count":4,"description":"","link":"https:\/\/ideoworks.id\/en\/tag\/agency-indonesia\/","name":"agency indonesia","slug":"agency-indonesia","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>agency indonesia Archives - IDEOWORKS<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"agency indonesia Archives - IDEOWORKS\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ideoworks.id\/en\/tag\/agency-indonesia\/\" \/>\n<meta property=\"og:site_name\" content=\"IDEOWORKS\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/ideoworks.id\/en\/tag\/agency-indonesia\/\",\"url\":\"https:\/\/ideoworks.id\/en\/tag\/agency-indonesia\/\",\"name\":\"agency indonesia Archives - IDEOWORKS\",\"isPartOf\":{\"@id\":\"https:\/\/ideoworks.id\/en\/#website\"},\"inLanguage\":\"en-US\"},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ideoworks.id\/en\/#website\",\"url\":\"https:\/\/ideoworks.id\/en\/\",\"name\":\"IDEOWORKS\",\"description\":\"Make Idea Works\",\"publisher\":{\"@id\":\"https:\/\/ideoworks.id\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ideoworks.id\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/ideoworks.id\/en\/#organization\",\"name\":\"IDEOWORKS\",\"url\":\"https:\/\/ideoworks.id\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/ideoworks.id\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/ideoworks.id\/en\/wp-content\/uploads\/2023\/10\/Logo-IDEOWORKS-white.svg\",\"contentUrl\":\"https:\/\/ideoworks.id\/en\/wp-content\/uploads\/2023\/10\/Logo-IDEOWORKS-white.svg\",\"width\":582,\"height\":70,\"caption\":\"IDEOWORKS\"},\"image\":{\"@id\":\"https:\/\/ideoworks.id\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"agency indonesia Archives - IDEOWORKS","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"agency indonesia Archives - IDEOWORKS","og_url":"https:\/\/ideoworks.id\/en\/tag\/agency-indonesia\/","og_site_name":"IDEOWORKS","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/ideoworks.id\/en\/tag\/agency-indonesia\/","url":"https:\/\/ideoworks.id\/en\/tag\/agency-indonesia\/","name":"agency indonesia Archives - IDEOWORKS","isPartOf":{"@id":"https:\/\/ideoworks.id\/en\/#website"},"inLanguage":"en-US"},{"@type":"WebSite","@id":"https:\/\/ideoworks.id\/en\/#website","url":"https:\/\/ideoworks.id\/en\/","name":"IDEOWORKS","description":"Make Idea Works","publisher":{"@id":"https:\/\/ideoworks.id\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ideoworks.id\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/ideoworks.id\/en\/#organization","name":"IDEOWORKS","url":"https:\/\/ideoworks.id\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/ideoworks.id\/en\/#\/schema\/logo\/image\/","url":"https:\/\/ideoworks.id\/en\/wp-content\/uploads\/2023\/10\/Logo-IDEOWORKS-white.svg","contentUrl":"https:\/\/ideoworks.id\/en\/wp-content\/uploads\/2023\/10\/Logo-IDEOWORKS-white.svg","width":582,"height":70,"caption":"IDEOWORKS"},"image":{"@id":"https:\/\/ideoworks.id\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/ideoworks.id\/en\/wp-json\/wp\/v2\/tags\/73","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ideoworks.id\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/ideoworks.id\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/ideoworks.id\/en\/wp-json\/wp\/v2\/posts?tags=73"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}